{"id":76,"count":10,"description":"Roundtable discussions with industry experts.","link":"https:\/\/avispl.es\/en\/resources\/webcasts\/","name":"On-Demand Webcasts","slug":"webcasts","taxonomy":"resource-category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>On-Demand Webcasts Archives - AVI-SPL Spain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avispl.es\/en\/resources\/webcasts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"On-Demand Webcasts Archives\" \/>\n<meta property=\"og:description\" content=\"Roundtable discussions with industry experts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avispl.es\/en\/resources\/webcasts\/\" \/>\n<meta property=\"og:site_name\" content=\"AVI-SPL Spain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/resources\\\/webcasts\\\/\",\"url\":\"https:\\\/\\\/avispl.es\\\/en\\\/resources\\\/webcasts\\\/\",\"name\":\"On-Demand Webcasts Archives - AVI-SPL Spain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/resources\\\/webcasts\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/resources\\\/webcasts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/avispl.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"On-Demand Webcasts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/avispl.es\\\/en\\\/\",\"name\":\"AVI-SPL Spain\",\"description\":\"AV\\\/UC collaboration, education and experience technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avispl.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/#organization\",\"name\":\"AVI-SPL\",\"url\":\"https:\\\/\\\/avispl.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avispl.es\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2024\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/avispl.es\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2024\\\/11\\\/logo.svg\",\"caption\":\"AVI-SPL\"},\"image\":{\"@id\":\"https:\\\/\\\/avispl.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"On-Demand Webcasts Archives - AVI-SPL Spain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avispl.es\/en\/resources\/webcasts\/","og_locale":"en_US","og_type":"article","og_title":"On-Demand Webcasts Archives","og_description":"Roundtable discussions with industry experts.","og_url":"https:\/\/avispl.es\/en\/resources\/webcasts\/","og_site_name":"AVI-SPL Spain","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/avispl.es\/en\/resources\/webcasts\/","url":"https:\/\/avispl.es\/en\/resources\/webcasts\/","name":"On-Demand Webcasts Archives - AVI-SPL Spain","isPartOf":{"@id":"https:\/\/avispl.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/avispl.es\/en\/resources\/webcasts\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/avispl.es\/en\/resources\/webcasts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/avispl.es\/en\/"},{"@type":"ListItem","position":2,"name":"On-Demand Webcasts"}]},{"@type":"WebSite","@id":"https:\/\/avispl.es\/en\/#website","url":"https:\/\/avispl.es\/en\/","name":"AVI-SPL Spain","description":"AV\/UC collaboration, education and experience technology","publisher":{"@id":"https:\/\/avispl.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avispl.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/avispl.es\/en\/#organization","name":"AVI-SPL","url":"https:\/\/avispl.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/avispl.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/avispl.es\/wp-content\/uploads\/sites\/21\/2024\/11\/logo.svg","contentUrl":"https:\/\/avispl.es\/wp-content\/uploads\/sites\/21\/2024\/11\/logo.svg","caption":"AVI-SPL"},"image":{"@id":"https:\/\/avispl.es\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avispl.es\/en\/wp-json\/wp\/v2\/resource-category\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avispl.es\/en\/wp-json\/wp\/v2\/resource-category"}],"about":[{"href":"https:\/\/avispl.es\/en\/wp-json\/wp\/v2\/taxonomies\/resource-category"}],"wp:post_type":[{"href":"https:\/\/avispl.es\/en\/wp-json\/wp\/v2\/resource?resource-category=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}